{"id":13475,"date":"2022-03-11T11:34:42","date_gmt":"2022-03-11T10:34:42","guid":{"rendered":"https:\/\/albergueesplaibarcelona.com\/?p=13475"},"modified":"2023-01-13T09:42:33","modified_gmt":"2023-01-13T08:42:33","slug":"test-turisme-sostenible","status":"publish","type":"post","link":"https:\/\/albergueesplaibarcelona.com\/ca\/blog-ca\/que_fer\/test-turisme-sostenible\/","title":{"rendered":"Test: Practiques el turisme sostenible?"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.10.8&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.10.8&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.10.8&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.10.8&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Quines ganes de viatjar! I \u00e9s que despr\u00e9s d&#8217;haver passat una pand\u00e8mia i d&#8217;haver respectat les restriccions,<strong> el desig de viatjar nom\u00e9s ha anat en augment<\/strong>! Ara, per fi, ja tenim m\u00e9s llibertat a l&#8217;hora de visitar altres pa\u00efsos, ciutats i pobles; i <strong>tenim l&#8217;oportunitat de fer-ho practicant un turisme de forma responsable i sostenible<\/strong>! S\u00ed, s\u00ed, parlem del <a href=\"https:\/\/ca.wikipedia.org\/wiki\/Turisme_responsable\"><em><strong>turisme sostenible<\/strong><\/em><\/a>. Ja saps qu\u00e8 \u00e9s?<\/p>\n<p>Segons l&#8217;<a href=\"https:\/\/www.unwto.org\/es\"><strong>Organitzaci\u00f3 Mundial del Turisme<\/strong><\/a> (OMT), el <strong><em>turisme sostenible<\/em><\/strong> \u00e9s \u00abaquell que t\u00e9 plenament en compte les repercussions actuals i futures, econ\u00f2miques, socials i mediambientals per satisfer les necessitats dels visitants, de la ind\u00fastria, de l&#8217;entorn i de les comunitats amfitriones\u00bb. Aix\u00ed doncs, entenem el turisme sostenible com un projecte que <strong>ha d&#8217;optimitzar els recursos mediambientals<\/strong> (en l&#8217;\u00e0mbit ecol\u00f2gic), que <strong>ha de protegir la cultura local<\/strong> (en l&#8217;\u00e0mbit social i cultural) i que <strong>ha de repartir de forma justa els guanys econ\u00f2mics entre tota la comunitat<\/strong> (en l&#8217;\u00e0mbit econ\u00f2mic)!<\/p>\n<p><a href=\"https:\/\/albergueesplaibarcelona.com\/ca\/blog-ca\/que_fer\/10-avantatges-de-practicar-turisme-sostenible\/\">&gt;&gt; Vols saber quins avantatges atorga el <em>turisme sostenible<\/em>?<\/a><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.10.8&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb30px||40px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center;\"><i class=\"fas fa-trees\"><\/i><strong> Sabies que, com a usuari, pots fer moltes accions per contribuir al <em>turisme sostenible<\/em>?<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2022\/03\/Nuevo-proyecto-51.jpg\u00bb alt=\u00bbturisme sostenible amb bicicletes\u00bb title_text=\u00bbturisme sostenible amb bicicletes\u00bb _builder_version=\u00bb4.10.8&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_divider _builder_version=\u00bb4.10.8&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb40px||30px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.10.8&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.10.8&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text admin_label=\u00bbPractiques el turisme sostenible?\u00bb _builder_version=\u00bb4.10.8&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||30px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Practiques el turisme sostenible?<\/h3>\n<p>[\/et_pb_text][et_pb_code admin_label=\u00bbCode Quizz\u00bb _builder_version=\u00bb4.10.8&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<script type=\"text\/javascript\" src=\"https:\/\/form.jotform.com\/jsform\/220652906852054\"><\/script>[\/et_pb_code][et_pb_text admin_label=\u00bbQu\u00e8 pots fer per ajudar al turisme sostenible?\u00bb _builder_version=\u00bb4.10.8&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb40px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Qu\u00e8 pots fer per ajudar al turisme sostenible?<\/h3>\n<p>Est\u00e0 clar, i ja ho hem pogut comprovar, que si no es gestiona b\u00e9 el turisme, aquest pot tenir un impacte molt negatiu en les comunitats i els medis ambients locals que pot ser origen de problemes a llarg termini per als residents. \u00c9s per aix\u00f2 que <strong>hi ha un seguit d&#8217;accions que s&#8217;han de complir per poder fer \u00fas de la paraula <\/strong><em><strong>turisme sostenible<\/strong>.\u00a0<\/em>Tant els governs, les institucions com nosaltres, els usuaris, hem de passar a l&#8217;acci\u00f3! <strong>Aqu\u00ed et deixem un seguit de consells que pots posar en pr\u00e0ctica de forma individual<\/strong>:<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.10.8&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb40px||||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb image=\u00bbhttps:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2019\/03\/numero1.png\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.10.8&#8243; custom_margin=\u00bb10px|10px|10px|10px\u00bb z_index_tablet=\u00bb500&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Allotja&#8217;t en <strong>hotels o <a href=\"https:\/\/albergueesplaibarcelona.com\/ca\/el-albergue\/eco-alberg\/\">albergs eficients<\/a>, ecol\u00f2gics <\/strong>i respectuosos amb el medi ambient.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb image=\u00bbhttps:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2019\/03\/numero2.png\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.10.8&#8243; custom_margin=\u00bb10px|10px|10px|10px\u00bb z_index_tablet=\u00bb500&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Mou-te en<strong> bicicleta, caminant o amb vehicles el\u00e8ctrics <\/strong>per impactar el m\u00ednim possible.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb image=\u00bbhttps:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2019\/03\/numero3.png\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.10.8&#8243; custom_margin=\u00bb10px|10px|10px|10px\u00bb z_index_tablet=\u00bb500&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Informa&#8217;t i <strong>respecta la cultura local <\/strong>de cada ciutat o poble que visitis.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb image=\u00bbhttps:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2019\/03\/numero4.png\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.10.8&#8243; custom_margin=\u00bb10px|10px|10px|10px\u00bb z_index_tablet=\u00bb500&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong>Evita imprimir bitllets, rutes, reserves o guies de viatge. <\/strong>Ara ho pots portar tot al m\u00f2bil sense gastar paper!<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb3.25&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb image=\u00bbhttps:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2019\/03\/numero5.png\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.10.8&#8243; custom_margin=\u00bb10px|10px|10px|10px\u00bb z_index_tablet=\u00bb500&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Fes un<strong> consum responsable de l&#8217;aigua. <\/strong>Hi ha pa\u00efsos que tenen reserves molt limitades.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb image=\u00bbhttps:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2019\/03\/numero6.png\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.10.8&#8243; custom_margin=\u00bb10px|10px|10px|10px\u00bb z_index_tablet=\u00bb500&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Ves a<strong> mercats o restaurants que tinguin productes de proximitat<\/strong> i Km 0.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb image=\u00bbhttps:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2019\/03\/numero7.png\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.10.8&#8243; custom_margin=\u00bb10px|10px|10px|10px\u00bb z_index_tablet=\u00bb500&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Intenta visitar ciutats o pobles que<strong> no estiguin molt massificats<\/strong>!<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb image=\u00bbhttps:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2019\/03\/numero8.png\u00bb icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.10.8&#8243; custom_margin=\u00bb10px|10px|10px|10px\u00bb z_index_tablet=\u00bb500&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Porta sempre una<strong> bossa de brossa amb tu<\/strong> per evitar deixar residus al teu pas i respectar l&#8217;entorn.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.10.8&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.10.8&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider _builder_version=\u00bb4.10.8&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb40px||30px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00bb4.10.8&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Esperem que aquests consells t&#8217;hagin animat a practicar<em> turisme sostenible<\/em> all\u00e0 on vulguis viatjar! I recorda que tamb\u00e9 <strong>pots utilitzar el cercador de <a href=\"https:\/\/www.biospheretourism.com\/es\/comunidad-de-destinos-turisticos-biosphere\/92\">Biosphere<\/a> per trobar aquella destinaci\u00f3 ideal per gaudir d&#8217;unes vacances sense augmentar la petjada ecol\u00f2gica<\/strong>!<\/p>\n<p>Se t&#8217;acudeixen m\u00e9s accions que puguin impactar de forma positiva al lloc visitant? Si \u00e9s aix\u00ed, no dubtis en dir-nos-ho!<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabies que, com a usuari, pots fer moltes accions per contribuir al turisme sostenible? Fes aquest test i descobreix com actuar!<\/p>\n","protected":false},"author":6,"featured_media":13537,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[33,134],"tags":[],"class_list":["post-13475","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-que_fer","category-sostenibilitat-ca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Test: Practiques el turisme sostenible? - Alberg Centre Esplai<\/title>\n<meta name=\"description\" content=\"Sabies que, com a usuari, pots fer moltes accions per contribuir al turisme sostenible? Fes aquest test i descobreix com actuar!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/albergueesplaibarcelona.com\/ca\/blog-ca\/que_fer\/test-turisme-sostenible\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Test: Practiques el turisme sostenible? - Alberg Centre Esplai\" \/>\n<meta property=\"og:description\" content=\"Sabies que, com a usuari, pots fer moltes accions per contribuir al turisme sostenible? Fes aquest test i descobreix com actuar!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/albergueesplaibarcelona.com\/ca\/blog-ca\/que_fer\/test-turisme-sostenible\/\" \/>\n<meta property=\"og:site_name\" content=\"Alberg Centre Esplai\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-11T10:34:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-13T08:42:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2022\/03\/Nuevo-proyecto-50.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1888\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cristina Espinosa Colom\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cristina Espinosa Colom\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/blog-ca\\\/que_fer\\\/test-turisme-sostenible\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/blog-ca\\\/que_fer\\\/test-turisme-sostenible\\\/\"},\"author\":{\"name\":\"Cristina Espinosa Colom\u00e9\",\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/#\\\/schema\\\/person\\\/207b9e504146116f51fecbd705c33396\"},\"headline\":\"Test: Practiques el turisme sostenible?\",\"datePublished\":\"2022-03-11T10:34:42+00:00\",\"dateModified\":\"2023-01-13T08:42:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/blog-ca\\\/que_fer\\\/test-turisme-sostenible\\\/\"},\"wordCount\":1105,\"publisher\":{\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/blog-ca\\\/que_fer\\\/test-turisme-sostenible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Nuevo-proyecto-50.jpg\",\"articleSection\":[\"Qu\u00e8 fer?\",\"Sostenibilitat\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/blog-ca\\\/que_fer\\\/test-turisme-sostenible\\\/\",\"url\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/blog-ca\\\/que_fer\\\/test-turisme-sostenible\\\/\",\"name\":\"Test: Practiques el turisme sostenible? - Alberg Centre Esplai\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/blog-ca\\\/que_fer\\\/test-turisme-sostenible\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/blog-ca\\\/que_fer\\\/test-turisme-sostenible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Nuevo-proyecto-50.jpg\",\"datePublished\":\"2022-03-11T10:34:42+00:00\",\"dateModified\":\"2023-01-13T08:42:33+00:00\",\"description\":\"Sabies que, com a usuari, pots fer moltes accions per contribuir al turisme sostenible? Fes aquest test i descobreix com actuar!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/blog-ca\\\/que_fer\\\/test-turisme-sostenible\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/blog-ca\\\/que_fer\\\/test-turisme-sostenible\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/blog-ca\\\/que_fer\\\/test-turisme-sostenible\\\/#primaryimage\",\"url\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Nuevo-proyecto-50.jpg\",\"contentUrl\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Nuevo-proyecto-50.jpg\",\"width\":1888,\"height\":900,\"caption\":\"Turisme sostenible portada Fundesplai\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/blog-ca\\\/que_fer\\\/test-turisme-sostenible\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/el-albergue\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/blog-ca\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Qu\u00e8 fer?\",\"item\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/blog-ca\\\/que_fer\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Test: Practiques el turisme sostenible?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/\",\"name\":\"Alberg Centre Esplai\",\"description\":\"Alberg\",\"publisher\":{\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/#organization\",\"name\":\"Albergue Centre Esplai\",\"url\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo_alberg_centre_esplai-e1608117409320.png\",\"contentUrl\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo_alberg_centre_esplai-e1608117409320.png\",\"width\":500,\"height\":241,\"caption\":\"Albergue Centre Esplai\"},\"image\":{\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/#\\\/schema\\\/person\\\/207b9e504146116f51fecbd705c33396\",\"name\":\"Cristina Espinosa Colom\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c055e483e79baf8f2898f968d705db458690241795f16b3e0ff8fd47bdac10e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c055e483e79baf8f2898f968d705db458690241795f16b3e0ff8fd47bdac10e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c055e483e79baf8f2898f968d705db458690241795f16b3e0ff8fd47bdac10e?s=96&d=mm&r=g\",\"caption\":\"Cristina Espinosa Colom\u00e9\"},\"url\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/ca\\\/author\\\/cespinosa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Test: Practiques el turisme sostenible? - Alberg Centre Esplai","description":"Sabies que, com a usuari, pots fer moltes accions per contribuir al turisme sostenible? Fes aquest test i descobreix com actuar!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/albergueesplaibarcelona.com\/ca\/blog-ca\/que_fer\/test-turisme-sostenible\/","og_locale":"ca_ES","og_type":"article","og_title":"Test: Practiques el turisme sostenible? - Alberg Centre Esplai","og_description":"Sabies que, com a usuari, pots fer moltes accions per contribuir al turisme sostenible? Fes aquest test i descobreix com actuar!","og_url":"https:\/\/albergueesplaibarcelona.com\/ca\/blog-ca\/que_fer\/test-turisme-sostenible\/","og_site_name":"Alberg Centre Esplai","article_published_time":"2022-03-11T10:34:42+00:00","article_modified_time":"2023-01-13T08:42:33+00:00","og_image":[{"width":1888,"height":900,"url":"https:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2022\/03\/Nuevo-proyecto-50.jpg","type":"image\/jpeg"}],"author":"Cristina Espinosa Colom\u00e9","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Cristina Espinosa Colom\u00e9","Temps estimat de lectura":"3 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/albergueesplaibarcelona.com\/ca\/blog-ca\/que_fer\/test-turisme-sostenible\/#article","isPartOf":{"@id":"https:\/\/albergueesplaibarcelona.com\/ca\/blog-ca\/que_fer\/test-turisme-sostenible\/"},"author":{"name":"Cristina Espinosa Colom\u00e9","@id":"https:\/\/albergueesplaibarcelona.com\/ca\/#\/schema\/person\/207b9e504146116f51fecbd705c33396"},"headline":"Test: Practiques el turisme sostenible?","datePublished":"2022-03-11T10:34:42+00:00","dateModified":"2023-01-13T08:42:33+00:00","mainEntityOfPage":{"@id":"https:\/\/albergueesplaibarcelona.com\/ca\/blog-ca\/que_fer\/test-turisme-sostenible\/"},"wordCount":1105,"publisher":{"@id":"https:\/\/albergueesplaibarcelona.com\/ca\/#organization"},"image":{"@id":"https:\/\/albergueesplaibarcelona.com\/ca\/blog-ca\/que_fer\/test-turisme-sostenible\/#primaryimage"},"thumbnailUrl":"https:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2022\/03\/Nuevo-proyecto-50.jpg","articleSection":["Qu\u00e8 fer?","Sostenibilitat"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/albergueesplaibarcelona.com\/ca\/blog-ca\/que_fer\/test-turisme-sostenible\/","url":"https:\/\/albergueesplaibarcelona.com\/ca\/blog-ca\/que_fer\/test-turisme-sostenible\/","name":"Test: Practiques el turisme sostenible? - Alberg Centre Esplai","isPartOf":{"@id":"https:\/\/albergueesplaibarcelona.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/albergueesplaibarcelona.com\/ca\/blog-ca\/que_fer\/test-turisme-sostenible\/#primaryimage"},"image":{"@id":"https:\/\/albergueesplaibarcelona.com\/ca\/blog-ca\/que_fer\/test-turisme-sostenible\/#primaryimage"},"thumbnailUrl":"https:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2022\/03\/Nuevo-proyecto-50.jpg","datePublished":"2022-03-11T10:34:42+00:00","dateModified":"2023-01-13T08:42:33+00:00","description":"Sabies que, com a usuari, pots fer moltes accions per contribuir al turisme sostenible? Fes aquest test i descobreix com actuar!","breadcrumb":{"@id":"https:\/\/albergueesplaibarcelona.com\/ca\/blog-ca\/que_fer\/test-turisme-sostenible\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/albergueesplaibarcelona.com\/ca\/blog-ca\/que_fer\/test-turisme-sostenible\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/albergueesplaibarcelona.com\/ca\/blog-ca\/que_fer\/test-turisme-sostenible\/#primaryimage","url":"https:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2022\/03\/Nuevo-proyecto-50.jpg","contentUrl":"https:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2022\/03\/Nuevo-proyecto-50.jpg","width":1888,"height":900,"caption":"Turisme sostenible portada Fundesplai"},{"@type":"BreadcrumbList","@id":"https:\/\/albergueesplaibarcelona.com\/ca\/blog-ca\/que_fer\/test-turisme-sostenible\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/albergueesplaibarcelona.com\/ca\/el-albergue\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/albergueesplaibarcelona.com\/ca\/blog-ca\/"},{"@type":"ListItem","position":3,"name":"Qu\u00e8 fer?","item":"https:\/\/albergueesplaibarcelona.com\/ca\/blog-ca\/que_fer\/"},{"@type":"ListItem","position":4,"name":"Test: Practiques el turisme sostenible?"}]},{"@type":"WebSite","@id":"https:\/\/albergueesplaibarcelona.com\/ca\/#website","url":"https:\/\/albergueesplaibarcelona.com\/ca\/","name":"Alberg Centre Esplai","description":"Alberg","publisher":{"@id":"https:\/\/albergueesplaibarcelona.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/albergueesplaibarcelona.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/albergueesplaibarcelona.com\/ca\/#organization","name":"Albergue Centre Esplai","url":"https:\/\/albergueesplaibarcelona.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/albergueesplaibarcelona.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2020\/12\/logo_alberg_centre_esplai-e1608117409320.png","contentUrl":"https:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2020\/12\/logo_alberg_centre_esplai-e1608117409320.png","width":500,"height":241,"caption":"Albergue Centre Esplai"},"image":{"@id":"https:\/\/albergueesplaibarcelona.com\/ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/albergueesplaibarcelona.com\/ca\/#\/schema\/person\/207b9e504146116f51fecbd705c33396","name":"Cristina Espinosa Colom\u00e9","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/5c055e483e79baf8f2898f968d705db458690241795f16b3e0ff8fd47bdac10e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5c055e483e79baf8f2898f968d705db458690241795f16b3e0ff8fd47bdac10e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c055e483e79baf8f2898f968d705db458690241795f16b3e0ff8fd47bdac10e?s=96&d=mm&r=g","caption":"Cristina Espinosa Colom\u00e9"},"url":"https:\/\/albergueesplaibarcelona.com\/ca\/author\/cespinosa\/"}]}},"_links":{"self":[{"href":"https:\/\/albergueesplaibarcelona.com\/ca\/wp-json\/wp\/v2\/posts\/13475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/albergueesplaibarcelona.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/albergueesplaibarcelona.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/albergueesplaibarcelona.com\/ca\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/albergueesplaibarcelona.com\/ca\/wp-json\/wp\/v2\/comments?post=13475"}],"version-history":[{"count":46,"href":"https:\/\/albergueesplaibarcelona.com\/ca\/wp-json\/wp\/v2\/posts\/13475\/revisions"}],"predecessor-version":[{"id":13573,"href":"https:\/\/albergueesplaibarcelona.com\/ca\/wp-json\/wp\/v2\/posts\/13475\/revisions\/13573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/albergueesplaibarcelona.com\/ca\/wp-json\/wp\/v2\/media\/13537"}],"wp:attachment":[{"href":"https:\/\/albergueesplaibarcelona.com\/ca\/wp-json\/wp\/v2\/media?parent=13475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/albergueesplaibarcelona.com\/ca\/wp-json\/wp\/v2\/categories?post=13475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/albergueesplaibarcelona.com\/ca\/wp-json\/wp\/v2\/tags?post=13475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}