{"id":6715,"date":"2019-10-22T14:13:36","date_gmt":"2019-10-22T14:13:36","guid":{"rendered":"https:\/\/albergueesplaibarcelona.com\/blog-en\/hostel-news\/how-do-the-hostels-solar-panels-work\/"},"modified":"2019-10-22T14:13:38","modified_gmt":"2019-10-22T14:13:38","slug":"how-do-the-hostels-solar-panels-work","status":"publish","type":"post","link":"https:\/\/albergueesplaibarcelona.com\/en\/blog-en\/hostel-news\/how-do-the-hostels-solar-panels-work\/","title":{"rendered":"How do the hostel&#8217;s solar panels work?"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;3.22.3&#8243;][et_pb_row _builder_version=&#8221;3.22.3&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.0.47&#8243;][et_pb_text _builder_version=&#8221;3.22.7&#8243; z_index_tablet=&#8221;500&#8243;]<\/p>\n<p>\u00a1Las energ\u00edas renovables son uno de nuestros temas estrella! \u00bfSab\u00edas que el <a href=\"https:\/\/albergueesplaibarcelona.com\/\">Alberg Centre Esplai<\/a> es un albergue ecol\u00f3gico y sostenible? <strong>Tiene un tejado enorme donde hemos instalado un elemento que nos ayuda a producir electricidad para todo el edificio: placas solares fotovoltaicas.\u00a0<\/strong><\/p>\n<p>La energ\u00eda que generan las placas solares se utiliza principalmente para abastecer en electricidad aparatos, casas, edificios, etc. Este tipo de energ\u00eda se comenz\u00f3 a usar de una forma m\u00e1s masiva a partir del a\u00f1o 2000, cuando <a href=\"https:\/\/books.google.es\/books?id=qGXvAgAAQBAJ&amp;pg=PA131&amp;redir_esc=y#v=onepage&amp;q&amp;f=false\">medioambientalistas alemanes y la organizaci\u00f3n Eurosolar obtuvieron financiaci\u00f3n para la creaci\u00f3n de diez millones de tejados solares<\/a>. Hoy en d\u00eda, la financiaci\u00f3n de este tipo de energ\u00eda ha aumentado y su implantaci\u00f3n se va normalizando cada vez m\u00e1s.<\/p>\n<p>Hoy te <strong>queremos explicar el funcionamiento de las placas solares fotovoltaicas: <\/strong>un poco m\u00e1s de informaci\u00f3n para ayudarte a subir al carro de las energ\u00edas renovables.\u00a0<\/p>\n<p>[\/et_pb_text][et_pb_divider _builder_version=&#8221;3.22.4&#8243; custom_margin=&#8221;40px||40px|&#8221; z_index_tablet=&#8221;500&#8243;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;3.22.3&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.0.47&#8243;][et_pb_text _builder_version=&#8221;3.22.7&#8243; z_index_tablet=&#8221;500&#8243;]<\/p>\n<ul>\n<li>\n<h3>Funcionamento de las placas solares<\/h3>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2019\/04\/infografia.jpg&#8221; align=&#8221;center&#8221; align_tablet=&#8221;center&#8221; align_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;3.23&#8243; custom_margin=&#8221;||40px|&#8221; z_index_tablet=&#8221;500&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;3.22.7&#8243; z_index_tablet=&#8221;500&#8243;]<\/p>\n<p>1. <strong>Las placas solares<\/strong> que tenemos en el Albergue Centre Esplai son las herramientas que usamos para obtener energ\u00eda renovable y que abarque todo el albergue. Estas placas est\u00e1n formadas por muchas celdas solares.<\/p>\n<p>2.<strong> Estas celdas solares<\/strong> de las que hemos hablado en el punto anterior, est\u00e1n formadas, a su vez, por peque\u00f1as c\u00e9lulas fotovoltaicas.<\/p>\n<p>3. <strong>\u00bfDe qu\u00e9 est\u00e1n formadas estas c\u00e9lulas? <\/strong>Ahora nos encontramos con la parte m\u00e1s interesante: las c\u00e9lulas fotovoltaicas est\u00e1n formadas por un elemento semiconductor nombrado Silicio donde predomina la carga negativa, pero tambi\u00e9n tiene electrones de carga positiva. El problema principal es juntar los dos tipos de carga para crear electricidad.<\/p>\n<p>4. <strong>\u00bfC\u00f3mo conseguimos, pues, que se junten las dos cargas? <\/strong>Es aqu\u00ed donde el Sol juega un papel esencial en el proceso de transformaci\u00f3n de energ\u00eda. El Sol env\u00eda fotones a las placas expuestas y hace que se muevan todos los electrones con carga negativa.<\/p>\n<p>5. As\u00ed pues, <strong>estos electrones con carga negativa se encuentran con los de carga positiva <\/strong>y generan la carga el\u00e9ctrica. Es decir, que se genera electricidad gracias a la luz solar y los elementos usados en las placas solares.<\/p>\n<p>[\/et_pb_text][et_pb_divider _builder_version=&#8221;3.23.3&#8243; custom_margin=&#8221;40px||40px&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;3.23.3&#8243;]<\/p>\n<p>Ahora que ya sabes c\u00f3mo funcionan las placas solares fotovoltaicas, <strong>puedes ver en el <a href=\"https:\/\/albergueesplaibarcelona.com\/el-albergue\/eco-albergue\/\">simulador de emisiones<\/a> como ha sido la implantaci\u00f3n de estas placas en el Albergue Centre Esplai<\/strong>. \u00a1Una gu\u00eda s\u00faper interesante!<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Las energ\u00edas renovables son uno de nuestros temas estrella! \u00bfSab\u00edas que el Alberg Centre Esplai es un albergue ecol\u00f3gico y sostenible? Tiene un tejado enorme donde hemos instalado un elemento que nos ayuda a producir electricidad para todo el edificio: placas solares fotovoltaicas.\u00a0La energ\u00eda que generan las placas solares se utiliza principalmente para abastecer en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3762,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"test","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[23,189],"tags":[],"class_list":["post-6715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hostel-news","category-sustainability"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>How do the hostel&#039;s solar panels work? - Albergue Centre Esplai<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/albergueesplaibarcelona.com\/en\/blog-en\/hostel-news\/how-do-the-hostels-solar-panels-work\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How do the hostel&#039;s solar panels work? - Albergue Centre Esplai\" \/>\n<meta property=\"og:description\" content=\"\u00a1Las energ\u00edas renovables son uno de nuestros temas estrella! \u00bfSab\u00edas que el Alberg Centre Esplai es un albergue ecol\u00f3gico y sostenible? Tiene un tejado enorme donde hemos instalado un elemento que nos ayuda a producir electricidad para todo el edificio: placas solares fotovoltaicas.\u00a0La energ\u00eda que generan las placas solares se utiliza principalmente para abastecer en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/albergueesplaibarcelona.com\/en\/blog-en\/hostel-news\/how-do-the-hostels-solar-panels-work\/\" \/>\n<meta property=\"og:site_name\" content=\"Albergue Centre Esplai\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-22T14:13:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-22T14:13:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2019\/05\/plaques2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2465\" \/>\n\t<meta property=\"og:image:height\" content=\"774\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Miquel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Miquel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/blog-en\\\/hostel-news\\\/how-do-the-hostels-solar-panels-work\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/blog-en\\\/hostel-news\\\/how-do-the-hostels-solar-panels-work\\\/\"},\"author\":{\"name\":\"Miquel\",\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/#\\\/schema\\\/person\\\/298d966724e84c57901bc05c8d161915\"},\"headline\":\"How do the hostel&#8217;s solar panels work?\",\"datePublished\":\"2019-10-22T14:13:36+00:00\",\"dateModified\":\"2019-10-22T14:13:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/blog-en\\\/hostel-news\\\/how-do-the-hostels-solar-panels-work\\\/\"},\"wordCount\":583,\"publisher\":{\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/blog-en\\\/hostel-news\\\/how-do-the-hostels-solar-panels-work\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/plaques2.jpg\",\"articleSection\":[\"Hostel news\",\"Sustainability\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/blog-en\\\/hostel-news\\\/how-do-the-hostels-solar-panels-work\\\/\",\"url\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/blog-en\\\/hostel-news\\\/how-do-the-hostels-solar-panels-work\\\/\",\"name\":\"How do the hostel's solar panels work? - Albergue Centre Esplai\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/blog-en\\\/hostel-news\\\/how-do-the-hostels-solar-panels-work\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/blog-en\\\/hostel-news\\\/how-do-the-hostels-solar-panels-work\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/plaques2.jpg\",\"datePublished\":\"2019-10-22T14:13:36+00:00\",\"dateModified\":\"2019-10-22T14:13:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/blog-en\\\/hostel-news\\\/how-do-the-hostels-solar-panels-work\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/blog-en\\\/hostel-news\\\/how-do-the-hostels-solar-panels-work\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/blog-en\\\/hostel-news\\\/how-do-the-hostels-solar-panels-work\\\/#primaryimage\",\"url\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/plaques2.jpg\",\"contentUrl\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/plaques2.jpg\",\"width\":2465,\"height\":774,\"caption\":\"Plaques Solars Fotovoltaiques\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/blog-en\\\/hostel-news\\\/how-do-the-hostels-solar-panels-work\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/blog-en\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hostel news\",\"item\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/blog-en\\\/hostel-news\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"How do the hostel&#8217;s solar panels work?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/\",\"name\":\"Albergue Centre Esplai\",\"description\":\"Alberg\",\"publisher\":{\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/#organization\",\"name\":\"Albergue Centre Esplai\",\"url\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo_alberg_centre_esplai-e1608117409320.png\",\"contentUrl\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/logo_alberg_centre_esplai-e1608117409320.png\",\"width\":500,\"height\":241,\"caption\":\"Albergue Centre Esplai\"},\"image\":{\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/#\\\/schema\\\/person\\\/298d966724e84c57901bc05c8d161915\",\"name\":\"Miquel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/464544cdbd75315146f2e2de9fa97073db157c4e2ef80a527d3ccfa975d62fb1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/464544cdbd75315146f2e2de9fa97073db157c4e2ef80a527d3ccfa975d62fb1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/464544cdbd75315146f2e2de9fa97073db157c4e2ef80a527d3ccfa975d62fb1?s=96&d=mm&r=g\",\"caption\":\"Miquel\"},\"url\":\"https:\\\/\\\/albergueesplaibarcelona.com\\\/en\\\/author\\\/marubio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"How do the hostel's solar panels work? - Albergue Centre Esplai","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/albergueesplaibarcelona.com\/en\/blog-en\/hostel-news\/how-do-the-hostels-solar-panels-work\/","og_locale":"en_US","og_type":"article","og_title":"How do the hostel's solar panels work? - Albergue Centre Esplai","og_description":"\u00a1Las energ\u00edas renovables son uno de nuestros temas estrella! \u00bfSab\u00edas que el Alberg Centre Esplai es un albergue ecol\u00f3gico y sostenible? Tiene un tejado enorme donde hemos instalado un elemento que nos ayuda a producir electricidad para todo el edificio: placas solares fotovoltaicas.\u00a0La energ\u00eda que generan las placas solares se utiliza principalmente para abastecer en [&hellip;]","og_url":"https:\/\/albergueesplaibarcelona.com\/en\/blog-en\/hostel-news\/how-do-the-hostels-solar-panels-work\/","og_site_name":"Albergue Centre Esplai","article_published_time":"2019-10-22T14:13:36+00:00","article_modified_time":"2019-10-22T14:13:38+00:00","og_image":[{"width":2465,"height":774,"url":"https:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2019\/05\/plaques2.jpg","type":"image\/jpeg"}],"author":"Miquel","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Miquel","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/albergueesplaibarcelona.com\/en\/blog-en\/hostel-news\/how-do-the-hostels-solar-panels-work\/#article","isPartOf":{"@id":"https:\/\/albergueesplaibarcelona.com\/en\/blog-en\/hostel-news\/how-do-the-hostels-solar-panels-work\/"},"author":{"name":"Miquel","@id":"https:\/\/albergueesplaibarcelona.com\/en\/#\/schema\/person\/298d966724e84c57901bc05c8d161915"},"headline":"How do the hostel&#8217;s solar panels work?","datePublished":"2019-10-22T14:13:36+00:00","dateModified":"2019-10-22T14:13:38+00:00","mainEntityOfPage":{"@id":"https:\/\/albergueesplaibarcelona.com\/en\/blog-en\/hostel-news\/how-do-the-hostels-solar-panels-work\/"},"wordCount":583,"publisher":{"@id":"https:\/\/albergueesplaibarcelona.com\/en\/#organization"},"image":{"@id":"https:\/\/albergueesplaibarcelona.com\/en\/blog-en\/hostel-news\/how-do-the-hostels-solar-panels-work\/#primaryimage"},"thumbnailUrl":"https:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2019\/05\/plaques2.jpg","articleSection":["Hostel news","Sustainability"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/albergueesplaibarcelona.com\/en\/blog-en\/hostel-news\/how-do-the-hostels-solar-panels-work\/","url":"https:\/\/albergueesplaibarcelona.com\/en\/blog-en\/hostel-news\/how-do-the-hostels-solar-panels-work\/","name":"How do the hostel's solar panels work? - Albergue Centre Esplai","isPartOf":{"@id":"https:\/\/albergueesplaibarcelona.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/albergueesplaibarcelona.com\/en\/blog-en\/hostel-news\/how-do-the-hostels-solar-panels-work\/#primaryimage"},"image":{"@id":"https:\/\/albergueesplaibarcelona.com\/en\/blog-en\/hostel-news\/how-do-the-hostels-solar-panels-work\/#primaryimage"},"thumbnailUrl":"https:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2019\/05\/plaques2.jpg","datePublished":"2019-10-22T14:13:36+00:00","dateModified":"2019-10-22T14:13:38+00:00","breadcrumb":{"@id":"https:\/\/albergueesplaibarcelona.com\/en\/blog-en\/hostel-news\/how-do-the-hostels-solar-panels-work\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/albergueesplaibarcelona.com\/en\/blog-en\/hostel-news\/how-do-the-hostels-solar-panels-work\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/albergueesplaibarcelona.com\/en\/blog-en\/hostel-news\/how-do-the-hostels-solar-panels-work\/#primaryimage","url":"https:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2019\/05\/plaques2.jpg","contentUrl":"https:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2019\/05\/plaques2.jpg","width":2465,"height":774,"caption":"Plaques Solars Fotovoltaiques"},{"@type":"BreadcrumbList","@id":"https:\/\/albergueesplaibarcelona.com\/en\/blog-en\/hostel-news\/how-do-the-hostels-solar-panels-work\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/albergueesplaibarcelona.com\/en\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/albergueesplaibarcelona.com\/en\/blog-en\/"},{"@type":"ListItem","position":3,"name":"Hostel news","item":"https:\/\/albergueesplaibarcelona.com\/en\/blog-en\/hostel-news\/"},{"@type":"ListItem","position":4,"name":"How do the hostel&#8217;s solar panels work?"}]},{"@type":"WebSite","@id":"https:\/\/albergueesplaibarcelona.com\/en\/#website","url":"https:\/\/albergueesplaibarcelona.com\/en\/","name":"Albergue Centre Esplai","description":"Alberg","publisher":{"@id":"https:\/\/albergueesplaibarcelona.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/albergueesplaibarcelona.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/albergueesplaibarcelona.com\/en\/#organization","name":"Albergue Centre Esplai","url":"https:\/\/albergueesplaibarcelona.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/albergueesplaibarcelona.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2020\/12\/logo_alberg_centre_esplai-e1608117409320.png","contentUrl":"https:\/\/albergueesplaibarcelona.com\/wp-content\/uploads\/2020\/12\/logo_alberg_centre_esplai-e1608117409320.png","width":500,"height":241,"caption":"Albergue Centre Esplai"},"image":{"@id":"https:\/\/albergueesplaibarcelona.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/albergueesplaibarcelona.com\/en\/#\/schema\/person\/298d966724e84c57901bc05c8d161915","name":"Miquel","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/464544cdbd75315146f2e2de9fa97073db157c4e2ef80a527d3ccfa975d62fb1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/464544cdbd75315146f2e2de9fa97073db157c4e2ef80a527d3ccfa975d62fb1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/464544cdbd75315146f2e2de9fa97073db157c4e2ef80a527d3ccfa975d62fb1?s=96&d=mm&r=g","caption":"Miquel"},"url":"https:\/\/albergueesplaibarcelona.com\/en\/author\/marubio\/"}]}},"_links":{"self":[{"href":"https:\/\/albergueesplaibarcelona.com\/en\/wp-json\/wp\/v2\/posts\/6715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/albergueesplaibarcelona.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/albergueesplaibarcelona.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/albergueesplaibarcelona.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/albergueesplaibarcelona.com\/en\/wp-json\/wp\/v2\/comments?post=6715"}],"version-history":[{"count":1,"href":"https:\/\/albergueesplaibarcelona.com\/en\/wp-json\/wp\/v2\/posts\/6715\/revisions"}],"predecessor-version":[{"id":6717,"href":"https:\/\/albergueesplaibarcelona.com\/en\/wp-json\/wp\/v2\/posts\/6715\/revisions\/6717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/albergueesplaibarcelona.com\/en\/wp-json\/wp\/v2\/media\/3762"}],"wp:attachment":[{"href":"https:\/\/albergueesplaibarcelona.com\/en\/wp-json\/wp\/v2\/media?parent=6715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/albergueesplaibarcelona.com\/en\/wp-json\/wp\/v2\/categories?post=6715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/albergueesplaibarcelona.com\/en\/wp-json\/wp\/v2\/tags?post=6715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}